{"id":10778,"date":"2015-09-21T12:06:31","date_gmt":"2015-09-21T10:06:31","guid":{"rendered":"http:\/\/www.bmscience.net\/blog\/?p=10778"},"modified":"2024-03-02T12:10:50","modified_gmt":"2024-03-02T11:10:50","slug":"cassini-rivela-un-oceano-globale-sulla-luna-encelado","status":"publish","type":"post","link":"https:\/\/bmscience.net\/blog\/cassini-rivela-un-oceano-globale-sulla-luna-encelado\/","title":{"rendered":"Cassini rivela un oceano globale sulla luna Encelado"},"content":{"rendered":"\n<p class=\"has-text-align-left\">Cassini non smette mai di stupirci. Oltre a numerose foto, ci invia dati importantissimi per capire il funzionamento del nostro sistema solare.<br>L&#8217;ultima scoperta fatta grazie alla sonda della NASA riguarda il sesto satellite naturale (in ordine di grandezza) di Saturno: Encelado.<\/p>\n\n\n\n<p class=\"has-text-align-left\">Fin ora si pensava fosse solamente una piccola luna congelata, ma grazie a Cassini, gli scienziati hanno scoperto che al di sotto dello strato di ghiaccio, il satellite nasconde un oceano che ne ricopre l&#8217;intera superficie.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft is-resized\"><a href=\"http:\/\/www.bmscience.net\/blog\/wp-content\/uploads\/2015\/09\/pia19656_labeled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"http:\/\/www.bmscience.net\/blog\/wp-content\/uploads\/2015\/09\/pia19656_labeled-300x169.jpg\" alt=\"pia19656_labeled\" class=\"wp-image-10780\" style=\"width:351px;height:auto\" srcset=\"https:\/\/bmscience.net\/blog\/wp-content\/uploads\/2015\/09\/pia19656_labeled-300x169.jpg 300w, https:\/\/bmscience.net\/blog\/wp-content\/uploads\/2015\/09\/pia19656_labeled-768x432.jpg 768w, https:\/\/bmscience.net\/blog\/wp-content\/uploads\/2015\/09\/pia19656_labeled.jpg 985w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-left\">Inizialmente si credeva che un piccolo giacimento di acqua allo stato liquido si trovasse solamente nei pressi del polo sud, dove si verificavano dei jet.<\/p>\n\n\n\n<p class=\"has-text-align-left\">Dopo anni di osservazioni e calcoli, per\u00f2, sono giunti alla conclusione che il giacimento \u00e8 molto pi\u00f9 grande di quello che si credeva.<\/p>\n\n\n\n<p class=\"has-text-align-left\">Comparando i moti di rotazione e oscillazione della luna con vari modelli, sono giunti a questa conclusione.<\/p>\n\n\n<div id=\"bmscience306848201\" style=\"margin-top: 15px;margin-left: 15px;float: right;\"><a href=\"https:\/\/amzn.to\/44ZclLw\" target=\"_blank\" aria-label=\"Progetto senza titolo\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/bmscience.net\/blog\/wp-content\/uploads\/2025\/07\/Progetto-senza-titolo-1.gif\" alt=\"\"  width=\"300\" height=\"300\"   \/><\/a><\/div>\n\n\n<p class=\"has-text-align-left\">Il motivo per cui il pianeta non \u00e8 completamente congelato, tuttavia, rimane ancora un mistero, ma alcune teorie possono spiegarlo, come per esempio la forza di gravit\u00e0 di Saturno.<\/p>\n\n\n\n<p class=\"has-text-align-left\">A causa dell&#8217;enorme gravit\u00e0 del pianeta, vengono generate delle&nbsp;forze di marea che potrebbero generare una discreta quantit\u00e0 di calore all&#8217;interno del nucleo roccioso di Encelado. Questo calore viene intrappolato dallo strato di ghiaccio che funge da isolante, permettendo la presenza di acqua allo stato liquido.<\/p>\n\n\n\n<p class=\"has-text-align-left\">Il prossimo volo ravvicinato su Encelado \u00e8 previsto per il 28 ottobre. La sonda voler\u00e0 a circa 50km dalla superficie della luna, sperando di ricavare nuove informazioni sul satellite e ovviamente regalarci nuovi scorci di un satellite distante pi\u00f9 di un miliardo di km dalla Terra.<\/p>\n\n\n<div id=\"bmscience3059619535\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><div data-id='24153' class='amazon-auto-links aal-js-loading'><p class='now-loading-placeholder'>Caricamento&#8230;<\/p><\/div>\r\n\r\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Cassini non smette mai di stupirci. Oltre a numerose foto, ci invia dati importantissimi per capire il funzionamento del nostro sistema solare.L&#8217;ultima scoperta fatta grazie alla sonda della NASA riguarda il sesto satellite naturale (in ordine di grandezza) di Saturno: Encelado. Fin ora si pensava fosse solamente una piccola luna congelata, ma grazie a Cassini,&hellip;<\/p>\n<p class=\"more\"><a class=\"more-link\" href=\"https:\/\/bmscience.net\/blog\/cassini-rivela-un-oceano-globale-sulla-luna-encelado\/\">Continue reading <span class=\"screen-reader-text\">Cassini rivela un oceano globale sulla luna Encelado<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":10949,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[30],"tags":[1376,2744,4546,5075,6583,6909],"class_list":["post-10778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spazio","tag-cassini","tag-encelado","tag-luna","tag-nasa","tag-saturno","tag-sistema-solare","entry"],"author_meta":{"display_name":"Stefano","author_link":"https:\/\/bmscience.net\/blog\/author\/stefano\/"},"featured_img":"https:\/\/bmscience.net\/blog\/wp-content\/uploads\/2015\/09\/enceladus-min-300x136.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/bmscience.net\/blog\/category\/spazio\/\" class=\"advgb-post-tax-term\">Spazio<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Spazio<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/bmscience.net\/blog\/category\/spazio\/\" class=\"advgb-post-tax-term\">cassini<\/a>","<a href=\"https:\/\/bmscience.net\/blog\/category\/spazio\/\" class=\"advgb-post-tax-term\">encelado<\/a>","<a href=\"https:\/\/bmscience.net\/blog\/category\/spazio\/\" class=\"advgb-post-tax-term\">Luna<\/a>","<a href=\"https:\/\/bmscience.net\/blog\/category\/spazio\/\" class=\"advgb-post-tax-term\">nasa<\/a>","<a href=\"https:\/\/bmscience.net\/blog\/category\/spazio\/\" class=\"advgb-post-tax-term\">saturno<\/a>","<a href=\"https:\/\/bmscience.net\/blog\/category\/spazio\/\" class=\"advgb-post-tax-term\">sistema solare<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">cassini<\/span>","<span class=\"advgb-post-tax-term\">encelado<\/span>","<span class=\"advgb-post-tax-term\">Luna<\/span>","<span class=\"advgb-post-tax-term\">nasa<\/span>","<span class=\"advgb-post-tax-term\">saturno<\/span>","<span class=\"advgb-post-tax-term\">sistema solare<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Pubblicato 11 anni fa","modified":"Aggiornato 2 anni fa"},"absolute_dates":{"created":"Pubblicato il 21\/09\/2015","modified":"Aggiornato il 02\/03\/2024"},"absolute_dates_time":{"created":"Pubblicato il 21\/09\/2015 12:06","modified":"Aggiornato il 02\/03\/2024 12:10"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/bmscience.net\/blog\/wp-json\/wp\/v2\/posts\/10778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bmscience.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bmscience.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bmscience.net\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bmscience.net\/blog\/wp-json\/wp\/v2\/comments?post=10778"}],"version-history":[{"count":0,"href":"https:\/\/bmscience.net\/blog\/wp-json\/wp\/v2\/posts\/10778\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bmscience.net\/blog\/wp-json\/wp\/v2\/media\/10949"}],"wp:attachment":[{"href":"https:\/\/bmscience.net\/blog\/wp-json\/wp\/v2\/media?parent=10778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bmscience.net\/blog\/wp-json\/wp\/v2\/categories?post=10778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bmscience.net\/blog\/wp-json\/wp\/v2\/tags?post=10778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}